{"id":11185,"date":"2023-08-21T14:08:08","date_gmt":"2023-08-21T14:08:08","guid":{"rendered":"https:\/\/maileon.com\/?page_id=11185"},"modified":"2024-04-30T23:18:10","modified_gmt":"2024-04-30T23:18:10","slug":"b2c-businesses","status":"publish","type":"page","link":"https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/","title":{"rendered":"B2C Businesses"},"content":{"rendered":"\n<div class=\"relative shape-hero-main block-hero-top-curve-sm block-hero-bottom-curve bg-primary bg-no-repeat bg-right-top bg-contain mb-14\">\n    <div\n        class=\"container relative text-primary flex flex-col justify-center items-start px-5 md:px-10 xl:px-40 pt-44 md:pt-64 lg:pt-20 pb-24 lg:pb-20 min-h-[681px] md:min-h-[607px] lg:min-h-[466px] xl:min-h-[656px]\"\n    >\n        <div class=\"flex flex-col w-full md:9\/12 lg:w-7\/12\">\n            \n                <h2 class=\"heading-1\">\n       B2C: Aumenta i risultati grazie ad un marketing conveniente\n    <\/h2>\n            <div class=\"prose prose-invert text-primary text-lg\">\n                <p>Sii protagonista tra le aziende B2C grazie all&#8217;email marketing automation e scopri il potenziale della comunicazione personalizzata come mai prima d&#8217;ora.<span class=\"EOP SCXW162077113 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:257}\">\u00a0<\/span><\/p>\n            <\/div>\n        <\/div>\n        <div class=\"flex flex-col md:flex-row w-full mt-4 gap-4\">\n                                                    <a href=\"https:\/\/maileon.com\/contact\" target=\"\" class=\"block btn btn-secondary\">\n        Contatti\n    <\/a>                                        <a href=\"https:\/\/maileon.com\/compare-marketing-automation-platforms\/\" target=\"\" class=\"block btn btn-primary-default\">\n        Confronta\n    <\/a>                                    <\/div>\n            <\/div>\n<\/div>\n\n\n<div class=\"container px-0 lg:px-10 xl:px-40 py-4 lg:py-16\">\n    <div class=\"grid grid-cols-1 lg:grid-cols-2 lg:gap-24 mb-8 \">\n                <div class=\" pb-6 md:pt-6\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2023\/08\/Maileon-Team3-resized-1024x683.jpg\" class=\"md:rounded-3xl w-full\" alt=\"\" srcset=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2023\/08\/Maileon-Team3-resized-1024x683.jpg 1024w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2023\/08\/Maileon-Team3-resized-300x200.jpg 300w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2023\/08\/Maileon-Team3-resized-768x512.jpg 768w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2023\/08\/Maileon-Team3-resized.jpg 1050w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>        <\/div>\n        <div class=\"lg:py-4 px-5 lg:px-0 lg:order-first\">\n            <div class=\"space-y-4\">\n                                <p class=\"text-gray-800 text-sm mb-4 mt-2\">\n                                    <\/p>\n                    <h1 class=\"heading-3 text-black\">\n       B2C: Automazione dell&#8217;email marketing\n    <\/h1>                <div class=\"prose\">\n                    <p>Sfrutta il potere della comunicazione personalizzata mentre ottimizziamo il raggiungimento dei tuoi clienti. Dai consigli automatizzati sui prodotti alle campagne promozionali programmate strategicamente, la nostra piattaforma massimizza il coinvolgimento e la conversione.\u00a0<strong>Migliora la tua strategia di marketing con facilit\u00e0<\/strong>\u00a0ed efficienza, connettendoti con il tuo pubblico in modi significativi che generano risultati.<\/p>\n                <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"container px-0 lg:px-10 xl:px-40 py-4 lg:py-16\">\n    <div class=\"grid grid-cols-1 lg:grid-cols-2 lg:gap-24 mb-8 \">\n                <div class=\" pb-6 md:pt-6\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_024_WEB-1024x682.jpg\" class=\"md:rounded-3xl w-full\" alt=\"\" srcset=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_024_WEB-1024x682.jpg 1024w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_024_WEB-300x200.jpg 300w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_024_WEB-768x512.jpg 768w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_024_WEB-1536x1024.jpg 1536w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_024_WEB.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>        <\/div>\n        <div class=\"lg:py-4 px-5 lg:px-0 \">\n            <div class=\"space-y-4\">\n                                <p class=\"text-gray-800 text-sm mb-4 mt-2\">\n                                    <\/p>\n                    <h2 class=\"heading-3 text-black\">\n       Personalizza Maileon in base alle esigenze della tua Azienda\n    <\/h2>                <div class=\"prose\">\n                    <p>Con piani flessibili e semplici opzioni di attivazione e disattivazione delle funzionalit\u00e0 Maileon, puoi aprire il tuo email marketing a molteplici possibilit\u00e0, dal principiante all&#8217;esperto.\u00a0<strong>Connettiti con la nostra libreria di partner tecnologici<\/strong>\u00a0per personalizzare e adattare il tuo email marketing alle tue esigenze, aggiungi nuove app come SMS, piattaforme di ricerca e merchandising o forse troverai il tuo sistema attuale gi\u00e0 nel mix. Oppure collabora con uno dei nostri molteplici partner di marketing specializzati nelle esigenze del tuo settore per ricevere ulteriore aiuto.<\/p>\n                <\/div>\n            <\/div>\n                            <div class=\"flex flex-col md:flex-row w-full mt-4 gap-4\">\n                                                                            <a href=\"https:\/\/maileon.com\/integrations\/\" target=\"\" class=\"block btn btn-secondary\">\n        Integrazioni\n    <\/a>                                                            <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<div class=\"container py-4 lg:py-14 px-0 \">\n    <div class=\" px-5 lg:px-10 xl:px-40 pb-3\">\n        <p class=\"text-gray-400 mx-0\">\n                    <\/p>\n        <div class=\"text-black mx-0 mb-8 lg:w-1\/2\">\n                <h2 class=\"heading-3\">\n       Storie di successo\n    <\/h2>        <\/div>\n        <div class=\"mb-10\">\n                    <\/div>\n        <div class=\"grid gap-4 xl:grid-cols-3\">\n                                    <a\n                class=\"group flex flex-col sm:flex-row xl:flex-col rounded-3xl border border-slate-900\/30 space-y-2 bg-primary relative overflow-hidden\"\n                href=\"https:\/\/maileon.com\/solutions\/cases\/spare-ribs-express\"\n                aria-label=\"Scopri di pi\u00f9\"\n                target=\"\"\n            >\n                <div class=\"relative basis-1\/3\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"627\" height=\"418\" src=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/12\/Spare-rib-express.png\" class=\"sm:h-36 xl:h-auto min-w-full min-h-full object-cover\" alt=\"\" srcset=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/12\/Spare-rib-express.png 627w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/12\/Spare-rib-express-300x200.png 300w\" sizes=\"auto, (max-width: 627px) 100vw, 627px\" \/>                    <div class=\"absolute -bottom-px w-full block sm:hidden xl:block\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 368 16\" preserveAspectRatio=\"none\" class=\"fill-primary\" >\n                            <path\n                                d=\"M368 10.3979L368 16L0.0417487 16L0.0417483 6.62934C0.0417483 6.62934 -4.89728 2.1648 92.6487 0.212572C190.195 -1.73965 368 10.3979 368 10.3979Z\"\n                            \/>\n                        <\/svg>\n                    <\/div>\n                    <div class=\"absolute top-0 right-0 h-full hidden sm:block xl:hidden\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" viewBox=\"0 0 16 149\" preserveAspectRatio=\"none\" class=\"h-full fill-primary\" >\n                            <path\n                                d=\"M10.3979 149H16V0.0169067H6.62933C6.62933 0.0169067 2.16478 -1.98288 0.21256 37.5126C-1.73966 77.0082 10.3979 149 10.3979 149Z\"\n                            \/>\n                        <\/svg>\n                    <\/div>\n                <\/div>\n\n                <div class=\"basis-2\/3 flex flex-col px-10 py-6 space-y-2 text-primary\">\n                    <span class=\"heading-4\">\n                        Spare Rib Express                    <\/span>\n                    <p class=\"\">\n                        Spare Rib Express \u00e8 nato ad Amsterdam nel 1992 con una formula di consegna pasti che eccelleva in qualit\u00e0, servizio e aspetto. Ha iniziato il franchising dopo quattro anni e vuole espandersi ulteriormente in Germania, Belgio e Paesi Bassi.                    <\/p>\n                    <div class=\"!mt-auto block text-right\">\n                            <svg \n        xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"h-5 ml-auto fill-secondary translate-x-0 group-hover:translate-x-2 transition-transform duration-500\" viewBox=\"0 0 20 20\"\n    >\n        <use xlink:href=\"#right-arrow\"><\/use>\n        <defs>\n            <path \n                id=\"right-arrow\" \n                fill-rule=\"evenodd\"\n                d=\"M10.293 3.293a1 1 0 011.414 0l6 6a1 1 0 010 1.414l-6 6a1 1 0 01-1.414-1.414L14.586 11H3a1 1 0 110-2h11.586l-4.293-4.293a1 1 0 010-1.414z\"\n                clip-rule=\"evenodd\" \n            \/>\n        <\/defs>\n    <\/svg>                    <\/div>\n                <\/div>\n            <\/a>\n                        <a\n                class=\"group flex flex-col sm:flex-row xl:flex-col rounded-3xl border border-slate-900\/30 space-y-2 bg-primary relative overflow-hidden\"\n                href=\"https:\/\/maileon.com\/solutions\/cases\/vote-company\"\n                aria-label=\"Scopri di pi\u00f9\"\n                target=\"\"\n            >\n                <div class=\"relative basis-1\/3\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"627\" height=\"418\" src=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/12\/vote-company.png\" class=\"sm:h-36 xl:h-auto min-w-full min-h-full object-cover\" alt=\"customer case vote company maileon\" srcset=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/12\/vote-company.png 627w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/12\/vote-company-300x200.png 300w\" sizes=\"auto, (max-width: 627px) 100vw, 627px\" \/>                    <div class=\"absolute -bottom-px w-full block sm:hidden xl:block\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 368 16\" preserveAspectRatio=\"none\" class=\"fill-primary\" >\n                            <path\n                                d=\"M368 10.3979L368 16L0.0417487 16L0.0417483 6.62934C0.0417483 6.62934 -4.89728 2.1648 92.6487 0.212572C190.195 -1.73965 368 10.3979 368 10.3979Z\"\n                            \/>\n                        <\/svg>\n                    <\/div>\n                    <div class=\"absolute top-0 right-0 h-full hidden sm:block xl:hidden\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" viewBox=\"0 0 16 149\" preserveAspectRatio=\"none\" class=\"h-full fill-primary\" >\n                            <path\n                                d=\"M10.3979 149H16V0.0169067H6.62933C6.62933 0.0169067 2.16478 -1.98288 0.21256 37.5126C-1.73966 77.0082 10.3979 149 10.3979 149Z\"\n                            \/>\n                        <\/svg>\n                    <\/div>\n                <\/div>\n\n                <div class=\"basis-2\/3 flex flex-col px-10 py-6 space-y-2 text-primary\">\n                    <span class=\"heading-4\">\n                        Vote Company                    <\/span>\n                    <p class=\"\">\n                        Vote Company \u00e8 lo specialista del voto in Benelux dal 2010. Dallo sviluppo, organizzazione e facilitazione di grandi premi pubblici, sondaggi e altro ancora come i Musical Awards, gli Zoover Awards e l&#8217;MKB Innovation Top 100 (KVK) a un voto conveniente, affidabile e sicuro strumento per le associazioni.                    <\/p>\n                    <div class=\"!mt-auto block text-right\">\n                            <svg \n        xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"h-5 ml-auto fill-secondary translate-x-0 group-hover:translate-x-2 transition-transform duration-500\" viewBox=\"0 0 20 20\"\n    >\n        <use xlink:href=\"#right-arrow\"><\/use>\n        <defs>\n            <path \n                id=\"right-arrow\" \n                fill-rule=\"evenodd\"\n                d=\"M10.293 3.293a1 1 0 011.414 0l6 6a1 1 0 010 1.414l-6 6a1 1 0 01-1.414-1.414L14.586 11H3a1 1 0 110-2h11.586l-4.293-4.293a1 1 0 010-1.414z\"\n                clip-rule=\"evenodd\" \n            \/>\n        <\/defs>\n    <\/svg>                    <\/div>\n                <\/div>\n            <\/a>\n                        <a\n                class=\"group flex flex-col sm:flex-row xl:flex-col rounded-3xl border border-slate-900\/30 space-y-2 bg-primary relative overflow-hidden\"\n                href=\"https:\/\/maileon.com\/solutions\/cases\"\n                aria-label=\"Scopri di pi\u00f9\"\n                target=\"\"\n            >\n                <div class=\"relative basis-1\/3\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"627\" height=\"418\" src=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/12\/418.png\" class=\"sm:h-36 xl:h-auto min-w-full min-h-full object-cover\" alt=\"More customer cases\" srcset=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/12\/418.png 627w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/12\/418-300x200.png 300w\" sizes=\"auto, (max-width: 627px) 100vw, 627px\" \/>                    <div class=\"absolute -bottom-px w-full block sm:hidden xl:block\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 368 16\" preserveAspectRatio=\"none\" class=\"fill-primary\" >\n                            <path\n                                d=\"M368 10.3979L368 16L0.0417487 16L0.0417483 6.62934C0.0417483 6.62934 -4.89728 2.1648 92.6487 0.212572C190.195 -1.73965 368 10.3979 368 10.3979Z\"\n                            \/>\n                        <\/svg>\n                    <\/div>\n                    <div class=\"absolute top-0 right-0 h-full hidden sm:block xl:hidden\">\n                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"16\" viewBox=\"0 0 16 149\" preserveAspectRatio=\"none\" class=\"h-full fill-primary\" >\n                            <path\n                                d=\"M10.3979 149H16V0.0169067H6.62933C6.62933 0.0169067 2.16478 -1.98288 0.21256 37.5126C-1.73966 77.0082 10.3979 149 10.3979 149Z\"\n                            \/>\n                        <\/svg>\n                    <\/div>\n                <\/div>\n\n                <div class=\"basis-2\/3 flex flex-col px-10 py-6 space-y-2 text-primary\">\n                    <span class=\"heading-4\">\n                        Storie di successo                    <\/span>\n                    <p class=\"\">\n                        Esplora alcuni dei nostri altri casi di clienti come Offspring Media o il rapporto cliente-partner con Spare Rib Express e Bikkelheart.                    <\/p>\n                    <div class=\"!mt-auto block text-right\">\n                            <svg \n        xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"h-5 ml-auto fill-secondary translate-x-0 group-hover:translate-x-2 transition-transform duration-500\" viewBox=\"0 0 20 20\"\n    >\n        <use xlink:href=\"#right-arrow\"><\/use>\n        <defs>\n            <path \n                id=\"right-arrow\" \n                fill-rule=\"evenodd\"\n                d=\"M10.293 3.293a1 1 0 011.414 0l6 6a1 1 0 010 1.414l-6 6a1 1 0 01-1.414-1.414L14.586 11H3a1 1 0 110-2h11.586l-4.293-4.293a1 1 0 010-1.414z\"\n                clip-rule=\"evenodd\" \n            \/>\n        <\/defs>\n    <\/svg>                    <\/div>\n                <\/div>\n            <\/a>\n                                <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"container px-0 lg:px-10 xl:px-40 py-4 lg:py-16\">\n    <div class=\"grid grid-cols-1 lg:grid-cols-2 lg:gap-24 mb-8 \">\n                <div class=\" pb-6 md:pt-6\">\n            <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"722\" src=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2023\/06\/Maileon-Device-1024x722.jpg\" class=\"md:rounded-3xl w-full\" alt=\"\" srcset=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2023\/06\/Maileon-Device-1024x722.jpg 1024w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2023\/06\/Maileon-Device-300x211.jpg 300w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2023\/06\/Maileon-Device-768x541.jpg 768w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2023\/06\/Maileon-Device.jpg 1050w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>        <\/div>\n        <div class=\"lg:py-4 px-5 lg:px-0 \">\n            <div class=\"space-y-4\">\n                                <p class=\"text-gray-800 text-sm mb-4 mt-2\">\n                                    <\/p>\n                    <h2 class=\"heading-3 text-black\">\n       ROI rapido ed efficienza dei costi\n    <\/h2>                <div class=\"prose\">\n                    <p><span>Sperimenta rapidi ritorni sul tuo investimento con Maileon. Con una comprovata esperienza nell&#8217;incremento delle conversioni e nell&#8217;incremento delle vendite, la nostra piattaforma garantisce che i tuoi sforzi di marketing si traducano direttamente in entrate. Il rapporto costo-efficacia della nostra soluzione risiede nella sua capacit\u00e0 di raggiungere un vasto pubblico con risorse minime, pur\u00a0<\/span><strong><span>trasmettendo messaggi personalizzati che abbiano risonanza<\/span><\/strong><span>\u00a0. D\u00ec addio alle spese inutili e dai il benvenuto a un approccio di marketing snello, efficiente e ad alto impatto che massimizza il ROI.<\/span><\/p>\n                <\/div>\n            <\/div>\n                            <div class=\"flex flex-col md:flex-row w-full mt-4 gap-4\">\n                                                                            <a href=\"https:\/\/maileon.com\/pricing\" target=\"\" class=\"block btn btn-secondary\">\n        Get your price\n    <\/a>                                                            <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div class=\"block-hero-top-curve-large bg-no-repeat bg-right-top bg-[length:auto_100%] relative overflow-hidden\">\n    <div class=\"relative lg:absolute lg:right-0 z-0 lg:w-1\/2 xl:w-3\/4 lg:mb-0 w-full\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_011_WEB-1024x684.jpg\" class=\"w-full min-w-[55vw] max-w-[100%]\" alt=\"Get in contact\" srcset=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_011_WEB-1024x684.jpg 1024w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_011_WEB-300x200.jpg 300w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_011_WEB-768x513.jpg 768w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_011_WEB-1536x1025.jpg 1536w, https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_011_WEB.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>        <div class=\"absolute bottom-0 w-full block lg:hidden\">\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 768 100\" class=\"fill-primary\">\n                <path\n                    d=\"M 1221,1000 H -63 c 0,0 6e-4,-745.425 0,-559.546 281.767,-44.575 673.208,42.792 843.517,65.08 170.308,22.288 359.343,4.457 440.483,-45.467 z\"\n                    id=\"path42\" clip-path=\"url(#clipPath289)\" transform=\"translate(0,-420.2691)\"\n                \/>\n            <\/svg>\n        <\/div>\n    <\/div>\n    <div class=\"shape-hero-cta bg-primary lg:bg-transparent bg-cover bg-left bg-no-repeat relative pb-20 md:pb-0 after:shape-hero-cta-bottom after:absolute after:top-0 after:bottom-0 after:bg-no-repeat after:bg-bottom after:bg-contain after:w-full after:pointer-events-none\">\n        <div class=\"container text-primary flex flex-col justify-center items-start px-5 md:px-10 xl:px-40 pt-8 lg:pt-20 pb-16 md:pb-32 lg:pb-20 lg:min-h-[429px] xl:min-h-[603px]\">\n            <div class=\"flex flex-col w-full lg:w-7\/12\">\n                \n                    <h3 class=\"heading-1\">\n       Parliamone!\n    <\/h3>\n                <div class=\"prose prose-invert text-primary text-lg\">\n                    <p>Che tu stia cercando nuove soluzioni software, una nuova partnership o semplicemente la possibilit\u00e0 di integrare i tuoi sistemi con <strong>Maileon<\/strong>,\u00a0 scrivici<br \/>\ncon <strong>fiducia<\/strong>!<\/p>\n                <\/div>\n            <\/div>\n            <div class=\"flex flex-col md:flex-row w-full mt-4 gap-4\">\n                                                                <a href=\"https:\/\/maileon.com\/contact\" target=\"\" class=\"block btn btn-secondary\">\n        Contatti\n    <\/a>                                                <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>You need a solution that allows for easy contact and connection with your customers at a cost-effective price.\u00a0\u00a0<\/p>\n","protected":false},"author":9,"featured_media":1463,"parent":7485,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[32,17],"class_list":["post-11185","page","type-page","status-publish","has-post-thumbnail","hentry","category-companies","category-industry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>B2C Businesses - Maileon<\/title>\n<meta name=\"description\" content=\"With Maileon you get a solution that allows for easy B2C marketing automation, for existing and potential customers. Discover more here.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"B2C Businesses\" \/>\n<meta property=\"og:description\" content=\"With Maileon you get a solution that allows for easy B2C marketing automation, for existing and potential customers. Discover more here.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/\" \/>\n<meta property=\"og:site_name\" content=\"Maileon\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-30T23:18:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_022_WEB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/solutions\\\/industries\\\/b2c-businesses\\\/\",\"url\":\"https:\\\/\\\/maileon.com\\\/it\\\/solutions\\\/industries\\\/b2c-businesses\\\/\",\"name\":\"B2C Businesses - Maileon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/solutions\\\/industries\\\/b2c-businesses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/solutions\\\/industries\\\/b2c-businesses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maileon.com\\\/app\\\/uploads\\\/sites\\\/6\\\/2022\\\/09\\\/BEELD31_Maileon_20220728_022_WEB.jpg\",\"datePublished\":\"2023-08-21T14:08:08+00:00\",\"dateModified\":\"2024-04-30T23:18:10+00:00\",\"description\":\"With Maileon you get a solution that allows for easy B2C marketing automation, for existing and potential customers. Discover more here.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/solutions\\\/industries\\\/b2c-businesses\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maileon.com\\\/it\\\/solutions\\\/industries\\\/b2c-businesses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/solutions\\\/industries\\\/b2c-businesses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maileon.com\\\/app\\\/uploads\\\/sites\\\/6\\\/2022\\\/09\\\/BEELD31_Maileon_20220728_022_WEB.jpg\",\"contentUrl\":\"https:\\\/\\\/maileon.com\\\/app\\\/uploads\\\/sites\\\/6\\\/2022\\\/09\\\/BEELD31_Maileon_20220728_022_WEB.jpg\",\"width\":2000,\"height\":1335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/solutions\\\/industries\\\/b2c-businesses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maileon.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solutions\",\"item\":\"https:\\\/\\\/maileon.com\\\/it\\\/solutions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Industries\",\"item\":\"https:\\\/\\\/maileon.com\\\/it\\\/solutions\\\/industries\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"B2C Businesses\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/maileon.com\\\/it\\\/\",\"name\":\"Maileon\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maileon.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/#organization\",\"name\":\"Maileon\",\"url\":\"https:\\\/\\\/maileon.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maileon.com\\\/app\\\/uploads\\\/sites\\\/6\\\/2022\\\/08\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/maileon.com\\\/app\\\/uploads\\\/sites\\\/6\\\/2022\\\/08\\\/logo.png\",\"width\":168,\"height\":33,\"caption\":\"Maileon\"},\"image\":{\"@id\":\"https:\\\/\\\/maileon.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"B2C Businesses - Maileon","description":"With Maileon you get a solution that allows for easy B2C marketing automation, for existing and potential customers. Discover more here.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"B2C Businesses","og_description":"With Maileon you get a solution that allows for easy B2C marketing automation, for existing and potential customers. Discover more here.","og_url":"https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/","og_site_name":"Maileon","article_modified_time":"2024-04-30T23:18:10+00:00","og_image":[{"width":2000,"height":1335,"url":"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_022_WEB.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/","url":"https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/","name":"B2C Businesses - Maileon","isPartOf":{"@id":"https:\/\/maileon.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/#primaryimage"},"image":{"@id":"https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/#primaryimage"},"thumbnailUrl":"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_022_WEB.jpg","datePublished":"2023-08-21T14:08:08+00:00","dateModified":"2024-04-30T23:18:10+00:00","description":"With Maileon you get a solution that allows for easy B2C marketing automation, for existing and potential customers. Discover more here.","breadcrumb":{"@id":"https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/#primaryimage","url":"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_022_WEB.jpg","contentUrl":"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/09\/BEELD31_Maileon_20220728_022_WEB.jpg","width":2000,"height":1335},{"@type":"BreadcrumbList","@id":"https:\/\/maileon.com\/it\/solutions\/industries\/b2c-businesses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maileon.com\/it\/"},{"@type":"ListItem","position":2,"name":"Solutions","item":"https:\/\/maileon.com\/it\/solutions\/"},{"@type":"ListItem","position":3,"name":"Industries","item":"https:\/\/maileon.com\/it\/solutions\/industries\/"},{"@type":"ListItem","position":4,"name":"B2C Businesses"}]},{"@type":"WebSite","@id":"https:\/\/maileon.com\/it\/#website","url":"https:\/\/maileon.com\/it\/","name":"Maileon","description":"","publisher":{"@id":"https:\/\/maileon.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maileon.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/maileon.com\/it\/#organization","name":"Maileon","url":"https:\/\/maileon.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/maileon.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/08\/logo.png","contentUrl":"https:\/\/maileon.com\/app\/uploads\/sites\/6\/2022\/08\/logo.png","width":168,"height":33,"caption":"Maileon"},"image":{"@id":"https:\/\/maileon.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/pages\/11185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/comments?post=11185"}],"version-history":[{"count":30,"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/pages\/11185\/revisions"}],"predecessor-version":[{"id":12290,"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/pages\/11185\/revisions\/12290"}],"up":[{"embeddable":true,"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/pages\/7485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/media\/1463"}],"wp:attachment":[{"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/media?parent=11185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maileon.com\/it\/wp-json\/wp\/v2\/categories?post=11185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}